{"id":7279,"date":"2026-09-02T11:49:04","date_gmt":"2026-09-02T09:49:04","guid":{"rendered":"https:\/\/uncjr.ro\/web\/?page_id=7279"},"modified":"2026-09-02T12:50:54","modified_gmt":"2026-09-02T10:50:54","slug":"rapoarte-activitate","status":"publish","type":"page","link":"https:\/\/uncjr.ro\/web\/rapoarte-activitate\/","title":{"rendered":"Rapoarte de activitate"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Rapoarte de activitate<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Raport de activitate UNCJR 2025&#8243; url=&#8221;https:\/\/uncjr.ro\/web\/wp-content\/uploads\/docs\/UNCJR_Raport_activitate_2025.pdf&#8221; url_new_window=&#8221;on&#8221; image=&#8221;https:\/\/uncjr.ro\/web\/wp-content\/uploads\/2026\/09\/uncjr_raport_activitate_2025.jpg&#8221; alt=&#8221;Raport de activitate 2025&#8243; icon_placement=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; image_icon_width_last_edited=&#8221;off|tablet&#8221; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h3&#8243; body_text_align=&#8221;justify&#8221; body_font_size=&#8221;16px&#8221; image_icon_custom_margin=&#8221;|1vw|||false|false&#8221; custom_margin=&#8221;||||false|false&#8221; link_option_url=&#8221;https:\/\/uncjr.ro\/web\/wp-content\/uploads\/docs\/UNCJR_Raport_activitate_2025.pdf&#8221; hover_enabled=&#8221;0&#8243; border_radii_image=&#8221;on|5px|5px|5px|5px&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; image__hover_enabled=&#8221;off|desktop&#8221; image_icon_width_tablet=&#8221;200px&#8221; icon_placement_last_edited=&#8221;on|tablet&#8221; icon_placement_phone=&#8221;top&#8221; icon_placement_tablet=&#8221;top&#8221; image_icon_width=&#8221;280px&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Adun\u0103rile generale ale UNCJR \u00een anul 2025<\/li>\n<li>Propuneri legislative ale UNCJR<\/li>\n<li>Interven\u021bii privind finan\u021barea de la bugetul de stat<\/li>\n<li>Interven\u021bii privind finan\u021barea european\u0103<\/li>\n<li>Consultarea UNCJR \u00een procedurile de adoptare a actelor normative<\/li>\n<li>Evenimente, grupuri\/comitete de lucru, dezbateri<\/li>\n<li>Proiecte cu finan\u021bare european\u0103 implementate de UNCJR<\/li>\n<li>Activitatea UNCJR pe plan european<\/li>\n<li>Quadruple helix \u2013 instrument strategic<\/li>\n<\/ul>\n<p><span style=\"font-size: 0.8em;\">(format PDF, 3.2MB)<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/uncjr.ro\/web\/wp-content\/uploads\/sigla-uncjr.png&#8221; alt=&#8221;UNCJR&#8221; title_text=&#8221;UNCJR&#8221; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; disabled_on=&#8221;on|on|off&#8221; sticky_enabled=&#8221;0&#8243; align=&#8221;right&#8221; width=&#8221;10vw&#8221; custom_margin=&#8221;2vw||||false|false&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_margin=&#8221;5vh||||false|false&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;2024&#8243; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf1c1;||fa||900&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;4em&#8221; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Raport de activitate pentru anul 2024<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rapoarte de activitate&nbsp; Adun\u0103rile generale ale UNCJR \u00een anul 2025 Propuneri legislative ale UNCJR Interven\u021bii privind finan\u021barea de la bugetul de stat Interven\u021bii privind finan\u021barea european\u0103 Consultarea UNCJR \u00een procedurile de adoptare a actelor normative Evenimente, grupuri\/comitete de lucru, dezbateri Proiecte cu finan\u021bare european\u0103 implementate de UNCJR Activitatea UNCJR pe plan european Quadruple helix \u2013 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-7279","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uncjr.ro\/web\/wp-json\/wp\/v2\/pages\/7279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uncjr.ro\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uncjr.ro\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uncjr.ro\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/uncjr.ro\/web\/wp-json\/wp\/v2\/comments?post=7279"}],"version-history":[{"count":11,"href":"https:\/\/uncjr.ro\/web\/wp-json\/wp\/v2\/pages\/7279\/revisions"}],"predecessor-version":[{"id":7302,"href":"https:\/\/uncjr.ro\/web\/wp-json\/wp\/v2\/pages\/7279\/revisions\/7302"}],"wp:attachment":[{"href":"https:\/\/uncjr.ro\/web\/wp-json\/wp\/v2\/media?parent=7279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}